{"id":47,"date":"2020-08-05T18:09:19","date_gmt":"2020-08-05T18:09:19","guid":{"rendered":"http:\/\/sites.unoeste.br\/ceofop\/?p=47"},"modified":"2020-09-09T18:18:28","modified_gmt":"2020-09-09T18:18:28","slug":"batata-doce-e-tema-de-webinar-e-acao-extensiva-da-unoeste","status":"publish","type":"post","link":"http:\/\/sites.unoeste.br\/ceofop\/index.php\/2020\/08\/05\/batata-doce-e-tema-de-webinar-e-acao-extensiva-da-unoeste\/","title":{"rendered":"Batata-doce \u00e9 tema de webinar e a\u00e7\u00e3o extensiva da Unoeste"},"content":{"rendered":"<p>Mais duas atividades na Unoeste est\u00e3o voltadas para contribuir com uma das principais culturas de Presidente Prudente e regi\u00e3o, geradora de emprego e renda. A primeira delas \u00e9 o 1\u00ba Webinar do Ceofop \u2013 Batata-doce: Manejo, Oportunidades e Divulga\u00e7\u00e3o de Resultados de Pesquisa, realizado pelo Centro de Estudos em Olericultura e Fruticultura do Oeste Paulista. A segunda ser\u00e1 o projeto de extens\u00e3o Fortalece Batata-Doce, a ser lan\u00e7ado durante o evento que \u00e9 aberto \u00e0 comunidade, gratuitamente.<\/p>\n<p>Conforme o professor pesquisador Dr. Andr\u00e9 Ricardo Zeist, o semin\u00e1rio atrav\u00e9s da web \u00e9 idealizado por membros do Ceofop, que tem como integrantes professores e alunos dos cursos de gradua\u00e7\u00e3o e p\u00f3s-gradua\u00e7\u00e3o em Agronomia. \u201cSurgiu a partir das atividades que esses cursos j\u00e1 realizam com a cultura da batata-doce\u201d, comenta. Ele diz ainda que o evento est\u00e1 voltado para a divulga\u00e7\u00e3o de resultados de pesquisa e tem a inten\u00e7\u00e3o de contribuir para o desenvolvimento sustent\u00e1vel e tecnol\u00f3gico da batata-doce, visando melhor atender as necessidades dos produtores e exig\u00eancias dos consumidores.<\/p>\n<p>Os temas abordados ser\u00e3o melhoramento gen\u00e9tico, manejo visando altas produtividades, m\u00faltiplos usos da batata-doce e rastreabilidade. A programa\u00e7\u00e3o ser\u00e1 aberta \u00e0s 19h no dia 11 de agosto, pr\u00f3xima ter\u00e7a-feira, com o tema \u201cBatata-doce: manejo visando altas produtividades\u201d, que ser\u00e1 desenvolvido pelo palestrante engenheiro agr\u00f4nomo Andr\u00e9 Longen, consultor da Interagro SP &#8211; Consultoria e Assessoria em Produ\u00e7\u00e3o Agropecu\u00e1ria. \u00c0s 20h, o engenheiro agr\u00f4nomo Felipe Rodrigues da Silva, do Caminho do Produtor, discorrer\u00e1 sobre \u201cRastreabilidade vegetal na cultura da datata-doce\u201d.<\/p>\n<p>No primeiro dia, atuar\u00e1 como debatedor o engenheiro agr\u00f4nomo Jos\u00e9 Corte, produtor de batata-doce e presidente da Associa\u00e7\u00e3o dos Produtores de Batata-doce de Presidente Prudente e regi\u00e3o (Aprobarpp). No dia 12, na quata-feira, o engenheiro agr\u00f4nomo Dr. Juliano Tadeu Vilela de Resende, vinculado \u00e0 Universidade de Londrina (UEL), falar\u00e1 sobre \u201cM\u00faltiplos usos da batata-doce: alimenta\u00e7\u00e3o humana, animal e produ\u00e7\u00e3o de \u00e1lcool\u201d. \u00c0s 20h, Zeist, tamb\u00e9m engenheiro agr\u00f4nomo, abordar\u00e1 o tema \u201cMelhoramento gen\u00e9tico da batata-doce e divulga\u00e7\u00e3o de resultados\u201d.<\/p>\n<p>Na condi\u00e7\u00e3o de debatedor, na segunda noite haver\u00e1 a participa\u00e7\u00e3o especial do engenheiro agr\u00f4nomo Marco Aur\u00e9lio Fernandes, da Secretaria de Agricultura e Abastecimento do Estado de S\u00e3o Paulo, diretor da Coordenadoria de Desenvolvimento Rural Sustent\u00e1vel (CDRS) Regional de Presidente Prudente.<\/p>\n<p>Adicionalmente na \u00faltima noite ocorrer\u00e1 o Lan\u00e7amento do projeto\/a\u00e7\u00e3o Fortalece Batata-Doce, pelo Lucas Feitosa, que \u00e9 Acad\u00eamico e Diretor-Presidente da Agripec Jr. da Agronomia Unoeste. Iniciativa que envolve a Pr\u00f3-Reitoria de Extens\u00e3o e A\u00e7\u00e3o Comunit\u00e1ria (Proext), professores dos cursos de gradua\u00e7\u00e3o e p\u00f3s-gradua\u00e7\u00e3o em Agronomia e a Agripec Jr. \u201cA inten\u00e7\u00e3o \u00e9 contribuir para o fortalecimento da batata-doce por meio de a\u00e7\u00f5es de extens\u00e3o que visar\u00e3o assessorar produtores, contribuindo para o aumento da produtividade e fortalecimento da cultura\u201d, diz Zeist.<\/p>\n<p>Com o patroc\u00ednio do Sicoob Paulista \u00e9 feita a aquisi\u00e7\u00e3o de batata-doce a ser doada para 30 entidades assistenciais que j\u00e1 s\u00e3o atendidas em a\u00e7\u00f5es sociais da Unoeste. Essa a\u00e7\u00e3o que faz parte do webinar foi idealizada junto A\u00e7\u00e3o idealizada pela Pr\u00f3-reitoria de Extens\u00e3o e A\u00e7\u00e3o Comunit\u00e1ria, Pr\u00f3-reitoria de Pesquisa e P\u00f3s-gradua\u00e7\u00e3o e cursos de gradua\u00e7\u00e3o e p\u00f3s-Gradua\u00e7\u00e3o em Agronomia.<\/p>\n<p>O p\u00fablico que j\u00e1 est\u00e1 sendo alcan\u00e7ado com as inscri\u00e7\u00f5es em andamento \u00e9 formado por agricultores, consultores, professores e estudantes, dentre outros. \u201cEstamos com mais de 140 inscritos, p\u00fablico de todas as regi\u00f5es do Brasil (mais de 10 estados) e inclusive uma inscri\u00e7\u00e3o da Bol\u00edvia\u201d, conta Ziest.<\/p>\n<p>O evento ser\u00e1 realizado por meio da plataforma Google Meet de forma gratuita e com emiss\u00e3o de certificado. Inscri\u00e7\u00f5es pelo site da Unoeste.<\/p>\n<p style=\"text-align: right;\">Not\u00edcia disponibilizada pela Assessoria de Imprensa da Unoeste<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mais duas atividades na Unoeste est\u00e3o voltadas para contribuir com uma das principais culturas de Presidente Prudente e regi\u00e3o, geradora de emprego e renda. A primeira delas \u00e9 o 1\u00ba Webinar do Ceofop \u2013 Batata-doce: Manejo, Oportunidades e Divulga\u00e7\u00e3o de Resultados de Pesquisa, realizado pelo &hellip; <\/p>\n","protected":false},"author":1,"featured_media":48,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"http:\/\/sites.unoeste.br\/ceofop\/index.php\/wp-json\/wp\/v2\/posts\/47"}],"collection":[{"href":"http:\/\/sites.unoeste.br\/ceofop\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sites.unoeste.br\/ceofop\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sites.unoeste.br\/ceofop\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/sites.unoeste.br\/ceofop\/index.php\/wp-json\/wp\/v2\/comments?post=47"}],"version-history":[{"count":1,"href":"http:\/\/sites.unoeste.br\/ceofop\/index.php\/wp-json\/wp\/v2\/posts\/47\/revisions"}],"predecessor-version":[{"id":49,"href":"http:\/\/sites.unoeste.br\/ceofop\/index.php\/wp-json\/wp\/v2\/posts\/47\/revisions\/49"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/sites.unoeste.br\/ceofop\/index.php\/wp-json\/wp\/v2\/media\/48"}],"wp:attachment":[{"href":"http:\/\/sites.unoeste.br\/ceofop\/index.php\/wp-json\/wp\/v2\/media?parent=47"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sites.unoeste.br\/ceofop\/index.php\/wp-json\/wp\/v2\/categories?post=47"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sites.unoeste.br\/ceofop\/index.php\/wp-json\/wp\/v2\/tags?post=47"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}