{"id":163,"date":"2020-09-30T18:11:35","date_gmt":"2020-09-30T18:11:35","guid":{"rendered":"http:\/\/sites.unoeste.br\/enepe\/?p=163"},"modified":"2020-10-23T17:09:22","modified_gmt":"2020-10-23T17:09:22","slug":"nivel-de-atividade-fisica-e-qualidade-de-vida-de-participantes-do-estudo-de-suplementacao-de-agua-ozonizada","status":"publish","type":"post","link":"http:\/\/sites.unoeste.br\/enepe\/index.php\/2020\/09\/30\/nivel-de-atividade-fisica-e-qualidade-de-vida-de-participantes-do-estudo-de-suplementacao-de-agua-ozonizada\/","title":{"rendered":"N\u00cdVEL DE ATIVIDADE F\u00cdSICA E QUALIDADE DE VIDA DE PARTICIPANTES DO ESTUDO DE SUPLEMENTA\u00c7\u00c3O DE \u00c1GUA OZONIZADA"},"content":{"rendered":"\n<p>Mar\u00edlia Esteves Alves de Souza, Maria Beatriz Tiezzi Vergara, Leticia Freire, Claudio Lera Orsatti<\/p>\n\n\n\n<p><a href=\"https:\/\/drive.google.com\/file\/d\/1oAPsNVAit7KfIuD0d1PHIjHZfuDqu8T0\/view?usp=drivesdk\">https:\/\/drive.google.com\/file\/d\/1oAPsNVAit7KfIuD0d1PHIjHZfuDqu8T0\/view?usp=drivesdk<\/a><\/p>\n\n\n\n<p>Baixo n\u00edvel de atividade f\u00edsica aliado ao estresse constante na vida dos de indiv\u00edduos urbanos pode interferir diretamente na qualidade de vida, favorecendo o desenvolvimento de fatores de risco para doen\u00e7as cr\u00f4nicas n\u00e3o transmiss\u00edveis. Muitas dessas condi\u00e7\u00f5es cr\u00f4nicas s\u00e3o conhecidas por terem o desenvolvimento iniciado ainda em idades jovens e progride lentamente por d\u00e9cadas at\u00e9 suas manifesta\u00e7\u00f5es cl\u00ednicas aparecerem. Assim tendo em vista a j\u00e1 transi\u00e7\u00e3o epidemiol\u00f3gica &#8211; esses dados podem refletir um atual panorama de estilo de vida.&nbsp;Correlacionar as caracter\u00edsticas cl\u00ednicas e o n\u00edvel de atividade f\u00edsica de indiv\u00edduos do estudo sobre o efeito da suplementa\u00e7\u00e3o isolada de \u00e1gua ozonizada.&nbsp;Estudo aprovado pelo CEP sob n\u00famero do CPDI: 5368 e CAAE: 32180420.7.0000.5515. A entrevista foi realizada com 59 participantes, foram coletados dados cl\u00ednicos como sexo, idade, n\u00famero de filhos, terapia hormonal, tabagismo, uso de medica\u00e7\u00e3o, conhecimento de \u00e1gua ozonizada e aplicado o Question\u00e1rio Internacional de Atividade F\u00edsica (IPAQ), abrangendo: caminhada, atividades moderadas e vigorosas e seus tempos de dura\u00e7\u00e3o, o tempo em que os participantes permanecem sentados durante dias de semana e de final de semana.&nbsp;A idade m\u00e9dia dos participantes \u00e9 de 21,7 anos, sendo 62,7% do sexo feminino e 37,3% masculino, 42,4% fazem uso de terapia hormonal, 1,7% tem filhos e 3,4% s\u00e3o tabagistas, 62,7% fazem uso de medica\u00e7\u00e3o, 23,7% conhecem \u00e1gua ozonizada. Esta popula\u00e7\u00e3o caminhou em m\u00e9dia 2,7 dias por semana, com dura\u00e7\u00e3o m\u00e9dia de 23 minutos, com rela\u00e7\u00e3o \u00e0s atividades moderadas verificou-se que h\u00e1 uma m\u00e9dia de 1,2 dias com tempo de dura\u00e7\u00e3o m\u00e9dio de 24,5 minutos, as atividades vigorosas tiveram m\u00e9dia de 1,23 dias e de tempo m\u00e9dio 22,45 minutos. O tempo sentado em dias de semana temos uma m\u00e9dia de 9,44 horas e em dias de final de semana 8,15 horas. A rela\u00e7\u00e3o de idade e tempo sentado em dias da semana mostrou-se significativa (p = 0,004).&nbsp;Quanto maior a idade menos tempo o indiv\u00edduo permanece sentado, sugerindo que nessa popula\u00e7\u00e3o busca melhor qualidade de vida com o passar dos anos de vida.&nbsp;Protocolo CAAE: 32180420.7.0000.5515&nbsp;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mar\u00edlia Esteves Alves de Souza, Maria Beatriz Tiezzi Vergara, Leticia Freire, Claudio Lera Orsatti<\/p>\n<p><\/p>\n<p><a href='https:\/\/drive.google.com\/file\/d\/1oAPsNVAit7KfIuD0d1PHIjHZfuDqu8T0\/view?usp=drivesdk' target='_blank' rel=\"noopener noreferrer\">https:\/\/drive.google.com\/file\/d\/1oAPsNVAit7KfIuD0d1PHIjHZfuDqu8T0\/view?usp=drivesdk<\/a><\/p>\n<p>Baixo n\u00edvel de atividade f\u00edsica aliado ao estresse constante na vida dos de indiv\u00edduos urbanos pode interferir diretamente na qualidade de vida, favorecendo o desenvolvimento de fatores de risco para doen\u00e7as cr\u00f4nicas n\u00e3o transmiss\u00edveis. Muitas dessas condi\u00e7\u00f5es cr\u00f4nicas s\u00e3o conhecidas por terem o desenvolvimento iniciado ainda em idades jovens e progride lentamente por d\u00e9cadas at\u00e9 suas manifesta\u00e7\u00f5es cl\u00ednicas aparecerem. Assim tendo em vista a j\u00e1 transi\u00e7\u00e3o epidemiol\u00f3gica &#8211; esses dados podem refletir um atual panorama de estilo de vida. Correlacionar as caracter\u00edsticas cl\u00ednicas e o n\u00edvel de atividade f\u00edsica de indiv\u00edduos do estudo sobre o efeito da suplementa\u00e7\u00e3o isolada de \u00e1gua ozonizada. Estudo aprovado pelo CEP sob n\u00famero do CPDI: 5368 e CAAE: 32180420.7.0000.5515. A entrevista foi realizada com 59 participantes, foram coletados dados cl\u00ednicos como sexo, idade, n\u00famero de filhos, terapia hormonal, tabagismo, uso de medica\u00e7\u00e3o, conhecimento de \u00e1gua ozonizada e aplicado o Question\u00e1rio Internacional de Atividade F\u00edsica (IPAQ), abrangendo: caminhada, atividades moderadas e vigorosas e seus tempos de dura\u00e7\u00e3o, o tempo em que os participantes permanecem sentados durante dias de semana e de final de semana. A idade m\u00e9dia dos participantes \u00e9 de 21,7 anos, sendo 62,7% do sexo feminino e 37,3% masculino, 42,4% fazem uso de terapia hormonal, 1,7% tem filhos e 3,4% s\u00e3o tabagistas, 62,7% fazem uso de medica\u00e7\u00e3o, 23,7% conhecem \u00e1gua ozonizada. Esta popula\u00e7\u00e3o caminhou em m\u00e9dia 2,7 dias por semana, com dura\u00e7\u00e3o m\u00e9dia de 23 minutos, com rela\u00e7\u00e3o \u00e0s atividades moderadas verificou-se que h\u00e1 uma m\u00e9dia de 1,2 dias com tempo de dura\u00e7\u00e3o m\u00e9dio de 24,5 minutos, as atividades vigorosas tiveram m\u00e9dia de 1,23 dias e de tempo m\u00e9dio 22,45 minutos. O tempo sentado em dias de semana temos uma m\u00e9dia de 9,44 horas e em dias de final de semana 8,15 horas. A rela\u00e7\u00e3o de idade e tempo sentado em dias da semana mostrou-se significativa (p = 0,004). Quanto maior a idade menos tempo o indiv\u00edduo permanece sentado, sugerindo que nessa popula\u00e7\u00e3o busca melhor qualidade de vida com o passar dos anos de vida. Protocolo CAAE: 32180420.7.0000.5515.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"http:\/\/sites.unoeste.br\/enepe\/index.php\/wp-json\/wp\/v2\/posts\/163"}],"collection":[{"href":"http:\/\/sites.unoeste.br\/enepe\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sites.unoeste.br\/enepe\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sites.unoeste.br\/enepe\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/sites.unoeste.br\/enepe\/index.php\/wp-json\/wp\/v2\/comments?post=163"}],"version-history":[{"count":3,"href":"http:\/\/sites.unoeste.br\/enepe\/index.php\/wp-json\/wp\/v2\/posts\/163\/revisions"}],"predecessor-version":[{"id":172,"href":"http:\/\/sites.unoeste.br\/enepe\/index.php\/wp-json\/wp\/v2\/posts\/163\/revisions\/172"}],"wp:attachment":[{"href":"http:\/\/sites.unoeste.br\/enepe\/index.php\/wp-json\/wp\/v2\/media?parent=163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sites.unoeste.br\/enepe\/index.php\/wp-json\/wp\/v2\/categories?post=163"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sites.unoeste.br\/enepe\/index.php\/wp-json\/wp\/v2\/tags?post=163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}